{"id":245025,"date":"2026-06-23T11:40:43","date_gmt":"2026-06-23T15:40:43","guid":{"rendered":"https:\/\/ibkrcampus.com\/campus\/?post_type=trading-lessons&#038;p=245025"},"modified":"2026-06-23T11:40:45","modified_gmt":"2026-06-23T15:40:45","slug":"orden-stop-en-ibkr-desktop","status":"publish","type":"trading-lessons","link":"https:\/\/www.interactivebrokers.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/","title":{"rendered":"Orden stop en IBKR Desktop"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las \u00f3rdenes stop se utilizan generalmente para cerrar una posici\u00f3n existente. Su objetivo es asegurar las ganancias o limitar las p\u00e9rdidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como alternativa, se puede crear una orden stop para obligar al inversor a abrir una nueva posici\u00f3n cuando se alcance un precio determinado. En este caso, se ha determinado optar por una posici\u00f3n larga si los precios superan un precio espec\u00edfico, o establecer una nueva posici\u00f3n corta si los precios caen por debajo de un umbral espec\u00edfico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El precio stop act\u00faa como un detonante que activar\u00e1 la orden cuando se alcance. &nbsp;Una orden stop pasa a ser negociable y est\u00e1 destinada a ejecutarse, independientemente del precio, una vez que se alcanza el precio de activaci\u00f3n determinado. No tiene un precio de ejecuci\u00f3n espec\u00edfico y puede ejecutarse muy lejos de su precio stop. En ese sentido, no es posible estimar el impacto de ejecutar lejos del precio de activaci\u00f3n, o precio stop, hasta que se haya completado la operaci\u00f3n.&nbsp; No obstante, tenga en cuenta que no se garantiza la ejecuci\u00f3n de las \u00f3rdenes stop, ya que es posible que no se activen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Creaci\u00f3n de una orden stop en IBKR Desktop<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El panel de \u00f3rdenes de IBKR Desktop se puede rellenar haciendo clic en un s\u00edmbolo en las pantallas Cartera o Lista de seguimiento, o escribiendo un s\u00edmbolo en la barra de b\u00fasqueda. Cuando haya seleccionado el s\u00edmbolo, el inversor puede hacer clic en &#8216;Comprar&#8217; o &#8216;Vender&#8217; para crear una ventana de orden. En este ejemplo, se decide crear una orden stop de venta para cerrar una posici\u00f3n existente en Meta si la acci\u00f3n cae por debajo de un precio determinado. Haga clic derecho en META en la cartera y seleccione &#8216;Cerrar posici\u00f3n&#8217; para rellenar el ticket de orden con la posici\u00f3n y configurarla como una orden de venta. Justo debajo hay tres tipos de \u00f3rdenes: limitada, mercado y stop. Elija &#8216;Stop&#8217; y, a continuaci\u00f3n, podr\u00e1 ajustar el precio stop en la siguiente l\u00ednea. El precio stop es el precio al que se activar\u00e1 la orden y pasar\u00e1 a ser negociable. &nbsp;Luego, seleccione el tiempo en vigor haciendo clic en el cuadro. Puede seleccionar &#8216;Intrad\u00eda&#8217; o V\u00e1lida hasta su cancelaci\u00f3n (&#8216;GTC&#8217;). En este escenario, se pretende mantener la orden stop activa despu\u00e9s de la sesi\u00f3n burs\u00e1til actual, por lo que se selecciona GTC. Para conocer mejor estos t\u00e9rminos, consulte el Glosario burs\u00e1til de IBKR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Env\u00edo de una orden stop en IBKR Desktop<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando est\u00e9 satisfecho con los datos introducidos en la orden, pulse &#8216;Vista previa&#8217; para ver un desglose de la orden, as\u00ed como su efecto sobre el margen, &#8216;Guardar&#8217; para guardar la orden y transmitirla m\u00e1s tarde, o &#8216;Enviar orden&#8217; para enviarla. Si elige &#8216;Enviar orden&#8217;, aparecer\u00e1 la pantalla de confirmaci\u00f3n de la orden. Una vez satisfecho, debe hacer clic en &#8216;Transmitir&#8217; para enviar la orden. Tras enviar la orden, si no se ejecuta, puede ver las operaciones, modificar la orden o cancelarla desde la pantalla de confirmaci\u00f3n de la orden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una orden stop es una instrucci\u00f3n para enviar una orden de mercado para comprar o vender siempre y cuando se alcance o sobrepase el precio de activaci\u00f3n stop especificado por el usuario. Una orden stop no garantiza un precio de ejecuci\u00f3n espec\u00edfico y puede ejecutarse muy lejos de su precio stop. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta lecci\u00f3n, definiremos el objetivo del tipo de orden stop y mostraremos c\u00f3mo crear una orden stop en IBKR Desktop.<\/p>\n","protected":false},"author":2,"featured_media":223965,"parent":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"contributors-categories":[13576],"traders-academy":[17005,18495],"class_list":["post-245025","trading-lessons","type-trading-lessons","status-publish","has-post-thumbnail","contributors-categories-interactive-brokers","traders-academy-language","traders-academy-es"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Archives | Traders&#039; Academy | IBKR Campus<\/title>\n<meta name=\"description\" content=\"En esta lecci\u00f3n, definiremos el objetivo del tipo de orden stop y mostraremos c\u00f3mo crear una orden stop en IBKR Desktop.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.interactivebrokers.com\/campus\/wp-json\/wp\/v2\/trading-lessons\/245025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orden stop en IBKR Desktop | IBKR Campus US\" \/>\n<meta property=\"og:description\" content=\"En esta lecci\u00f3n, definiremos el objetivo del tipo de orden stop y mostraremos c\u00f3mo crear una orden stop en IBKR Desktop.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.interactivebrokers.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/\" \/>\n<meta property=\"og:site_name\" content=\"IBKR Campus US\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T15:40:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2025\/05\/stop-order-thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/orden-stop-en-ibkr-desktop\\\/\",\n\t            \"url\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/orden-stop-en-ibkr-desktop\\\/\",\n\t            \"name\": \"Orden stop en IBKR Desktop | IBKR Campus US\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#website\"\n\t            },\n\t            \"primaryImageOfPage\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/orden-stop-en-ibkr-desktop\\\/#primaryimage\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/orden-stop-en-ibkr-desktop\\\/#primaryimage\"\n\t            },\n\t            \"thumbnailUrl\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/stop-order-thumbnail.jpg\",\n\t            \"datePublished\": \"2026-06-23T15:40:43+00:00\",\n\t            \"dateModified\": \"2026-06-23T15:40:45+00:00\",\n\t            \"description\": \"En esta lecci\u00f3n, definiremos el objetivo del tipo de orden stop y mostraremos c\u00f3mo crear una orden stop en IBKR Desktop.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/orden-stop-en-ibkr-desktop\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"en-US\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/orden-stop-en-ibkr-desktop\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"ImageObject\",\n\t            \"inLanguage\": \"en-US\",\n\t            \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/orden-stop-en-ibkr-desktop\\\/#primaryimage\",\n\t            \"url\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/stop-order-thumbnail.jpg\",\n\t            \"contentUrl\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/05\\\/stop-order-thumbnail.jpg\",\n\t            \"width\": 1920,\n\t            \"height\": 1080\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/orden-stop-en-ibkr-desktop\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Academy Lessons\",\n\t                    \"item\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/trading-lessons\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Orden stop en IBKR Desktop\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/\",\n\t            \"name\": \"IBKR Campus US\",\n\t            \"description\": \"Financial Education from Interactive Brokers\",\n\t            \"publisher\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#organization\"\n\t            },\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"en-US\"\n\t        },\n\t        {\n\t            \"@type\": \"Organization\",\n\t            \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#organization\",\n\t            \"name\": \"Interactive Brokers\",\n\t            \"alternateName\": \"IBKR\",\n\t            \"url\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/\",\n\t            \"logo\": {\n\t                \"@type\": \"ImageObject\",\n\t                \"inLanguage\": \"en-US\",\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\n\t                \"url\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/ibkr-campus-logo.jpg\",\n\t                \"contentUrl\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/ibkr-campus-logo.jpg\",\n\t                \"width\": 669,\n\t                \"height\": 669,\n\t                \"caption\": \"Interactive Brokers\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#\\\/schema\\\/logo\\\/image\\\/\"\n\t            },\n\t            \"publishingPrinciples\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/about-ibkr-campus\\\/\",\n\t            \"ethicsPolicy\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/cyber-security-notice\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Archives | Traders' Academy | IBKR Campus","description":"En esta lecci\u00f3n, definiremos el objetivo del tipo de orden stop y mostraremos c\u00f3mo crear una orden stop en IBKR Desktop.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.interactivebrokers.com\/campus\/wp-json\/wp\/v2\/trading-lessons\/245025\/","og_locale":"en_US","og_type":"article","og_title":"Orden stop en IBKR Desktop | IBKR Campus US","og_description":"En esta lecci\u00f3n, definiremos el objetivo del tipo de orden stop y mostraremos c\u00f3mo crear una orden stop en IBKR Desktop.","og_url":"https:\/\/www.interactivebrokers.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/","og_site_name":"IBKR Campus US","article_modified_time":"2026-06-23T15:40:45+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2025\/05\/stop-order-thumbnail.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibkrcampus.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/","url":"https:\/\/ibkrcampus.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/","name":"Orden stop en IBKR Desktop | IBKR Campus US","isPartOf":{"@id":"https:\/\/ibkrcampus.com\/campus\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibkrcampus.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/#primaryimage"},"image":{"@id":"https:\/\/ibkrcampus.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2025\/05\/stop-order-thumbnail.jpg","datePublished":"2026-06-23T15:40:43+00:00","dateModified":"2026-06-23T15:40:45+00:00","description":"En esta lecci\u00f3n, definiremos el objetivo del tipo de orden stop y mostraremos c\u00f3mo crear una orden stop en IBKR Desktop.","breadcrumb":{"@id":"https:\/\/ibkrcampus.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibkrcampus.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ibkrcampus.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/#primaryimage","url":"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2025\/05\/stop-order-thumbnail.jpg","contentUrl":"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2025\/05\/stop-order-thumbnail.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ibkrcampus.com\/campus\/trading-lessons\/orden-stop-en-ibkr-desktop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Academy Lessons","item":"https:\/\/ibkrcampus.com\/campus\/trading-lessons\/"},{"@type":"ListItem","position":2,"name":"Orden stop en IBKR Desktop"}]},{"@type":"WebSite","@id":"https:\/\/ibkrcampus.com\/campus\/#website","url":"https:\/\/ibkrcampus.com\/campus\/","name":"IBKR Campus US","description":"Financial Education from Interactive Brokers","publisher":{"@id":"https:\/\/ibkrcampus.com\/campus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibkrcampus.com\/campus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ibkrcampus.com\/campus\/#organization","name":"Interactive Brokers","alternateName":"IBKR","url":"https:\/\/ibkrcampus.com\/campus\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ibkrcampus.com\/campus\/#\/schema\/logo\/image\/","url":"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2024\/05\/ibkr-campus-logo.jpg","contentUrl":"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2024\/05\/ibkr-campus-logo.jpg","width":669,"height":669,"caption":"Interactive Brokers"},"image":{"@id":"https:\/\/ibkrcampus.com\/campus\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/www.interactivebrokers.com\/campus\/about-ibkr-campus\/","ethicsPolicy":"https:\/\/www.interactivebrokers.com\/campus\/cyber-security-notice\/"}]}},"_links":{"self":[{"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/trading-lessons\/245025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/trading-lessons"}],"about":[{"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/types\/trading-lessons"}],"author":[{"embeddable":true,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/comments?post=245025"}],"version-history":[{"count":1,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/trading-lessons\/245025\/revisions"}],"predecessor-version":[{"id":245055,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/trading-lessons\/245025\/revisions\/245055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/media\/223965"}],"wp:attachment":[{"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/media?parent=245025"}],"wp:term":[{"taxonomy":"contributors-categories","embeddable":true,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/contributors-categories?post=245025"},{"taxonomy":"traders-academy","embeddable":true,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/traders-academy?post=245025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}