{"id":179646,"date":"2021-05-24T13:08:00","date_gmt":"2021-05-24T17:08:00","guid":{"rendered":"https:\/\/ibkrcampus.com\/glossary-terms\/todays-top-ten-news\/"},"modified":"2023-01-22T13:32:44","modified_gmt":"2023-01-22T18:32:44","slug":"todays-top-ten-news","status":"publish","type":"glossary-terms","link":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/todays-top-ten-news\/","title":{"rendered":"Today&#8217;s Top Ten News"},"content":{"rendered":"<p>Subscribers with a Dow Jones news subscription can elect to view the DJ Today&#8217;s Top Ten items by adding Top Ten from the News panel.  &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Subscribers with a Dow Jones news subscription can elect to view the DJ Today&#8217;s Top Ten items by adding Top Ten from the News panel. &nbsp;<\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"traders-glossary":[13258,13251],"class_list":["post-179646","glossary-terms","type-glossary-terms","status-publish","traders-glossary-trading-terms-t","traders-glossary-trading-alphabet"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Archives Term | IBKR Glossary | IBKR Campus<\/title>\n<meta name=\"description\" content=\"Subscribers with a Dow Jones news subscription can elect to view the DJ Today&#039;s Top Ten items by adding Top Ten from the News panel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.interactivebrokers.com\/campus\/wp-json\/wp\/v2\/glossary-terms\/179646\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Today&#039;s Top Ten News Dow Jones\" \/>\n<meta property=\"og:description\" content=\"Subscribers with a Dow Jones news subscription can elect to view the DJ Today&#039;s Top Ten items by adding Top Ten from the News panel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/todays-top-ten-news\/\" \/>\n<meta property=\"og:site_name\" content=\"IBKR Campus US\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-22T18:32:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Today&#039;s Top Ten News Dow Jones\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/todays-top-ten-news\\\/\",\n\t            \"url\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/todays-top-ten-news\\\/\",\n\t            \"name\": \"Today's Top Ten News Dow Jones\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2021-05-24T17:08:00+00:00\",\n\t            \"dateModified\": \"2023-01-22T18:32:44+00:00\",\n\t            \"description\": \"Subscribers with a Dow Jones news subscription can elect to view the DJ Today's Top Ten items by adding Top Ten from the News panel.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/todays-top-ten-news\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"en-US\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/todays-top-ten-news\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/todays-top-ten-news\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Glossary\",\n\t                    \"item\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/glossary-terms\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Today&#8217;s Top Ten News\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/\",\n\t            \"name\": \"IBKR Campus US\",\n\t            \"description\": \"Financial Education from Interactive Brokers\",\n\t            \"publisher\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#organization\"\n\t            },\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"en-US\"\n\t        },\n\t        {\n\t            \"@type\": \"Organization\",\n\t            \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#organization\",\n\t            \"name\": \"Interactive Brokers\",\n\t            \"alternateName\": \"IBKR\",\n\t            \"url\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/\",\n\t            \"logo\": {\n\t                \"@type\": \"ImageObject\",\n\t                \"inLanguage\": \"en-US\",\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#\\\/schema\\\/logo\\\/image\\\/\",\n\t                \"url\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/ibkr-campus-logo.jpg\",\n\t                \"contentUrl\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/05\\\/ibkr-campus-logo.jpg\",\n\t                \"width\": 669,\n\t                \"height\": 669,\n\t                \"caption\": \"Interactive Brokers\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.com\\\/campus\\\/#\\\/schema\\\/logo\\\/image\\\/\"\n\t            },\n\t            \"publishingPrinciples\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/about-ibkr-campus\\\/\",\n\t            \"ethicsPolicy\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/cyber-security-notice\\\/\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Archives Term | IBKR Glossary | IBKR Campus","description":"Subscribers with a Dow Jones news subscription can elect to view the DJ Today's Top Ten items by adding Top Ten from the News panel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.interactivebrokers.com\/campus\/wp-json\/wp\/v2\/glossary-terms\/179646\/","og_locale":"en_US","og_type":"article","og_title":"Today's Top Ten News Dow Jones","og_description":"Subscribers with a Dow Jones news subscription can elect to view the DJ Today's Top Ten items by adding Top Ten from the News panel.","og_url":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/todays-top-ten-news\/","og_site_name":"IBKR Campus US","article_modified_time":"2023-01-22T18:32:44+00:00","twitter_card":"summary_large_image","twitter_title":"Today's Top Ten News Dow Jones","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/todays-top-ten-news\/","url":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/todays-top-ten-news\/","name":"Today's Top Ten News Dow Jones","isPartOf":{"@id":"https:\/\/ibkrcampus.com\/campus\/#website"},"datePublished":"2021-05-24T17:08:00+00:00","dateModified":"2023-01-22T18:32:44+00:00","description":"Subscribers with a Dow Jones news subscription can elect to view the DJ Today's Top Ten items by adding Top Ten from the News panel.","breadcrumb":{"@id":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/todays-top-ten-news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/todays-top-ten-news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/todays-top-ten-news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Glossary","item":"https:\/\/ibkrcampus.com\/campus\/glossary-terms\/"},{"@type":"ListItem","position":2,"name":"Today&#8217;s Top Ten News"}]},{"@type":"WebSite","@id":"https:\/\/ibkrcampus.com\/campus\/#website","url":"https:\/\/ibkrcampus.com\/campus\/","name":"IBKR Campus US","description":"Financial Education from Interactive Brokers","publisher":{"@id":"https:\/\/ibkrcampus.com\/campus\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibkrcampus.com\/campus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ibkrcampus.com\/campus\/#organization","name":"Interactive Brokers","alternateName":"IBKR","url":"https:\/\/ibkrcampus.com\/campus\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ibkrcampus.com\/campus\/#\/schema\/logo\/image\/","url":"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2024\/05\/ibkr-campus-logo.jpg","contentUrl":"https:\/\/www.interactivebrokers.com\/campus\/wp-content\/uploads\/sites\/2\/2024\/05\/ibkr-campus-logo.jpg","width":669,"height":669,"caption":"Interactive Brokers"},"image":{"@id":"https:\/\/ibkrcampus.com\/campus\/#\/schema\/logo\/image\/"},"publishingPrinciples":"https:\/\/www.interactivebrokers.com\/campus\/about-ibkr-campus\/","ethicsPolicy":"https:\/\/www.interactivebrokers.com\/campus\/cyber-security-notice\/"}]}},"_links":{"self":[{"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/glossary-terms\/179646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/glossary-terms"}],"about":[{"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/types\/glossary-terms"}],"version-history":[{"count":0,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/glossary-terms\/179646\/revisions"}],"wp:attachment":[{"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/media?parent=179646"}],"wp:term":[{"taxonomy":"traders-glossary","embeddable":true,"href":"https:\/\/ibkrcampus.com\/campus\/wp-json\/wp\/v2\/traders-glossary?post=179646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}